{"id":21657,"date":"2024-07-24T11:03:43","date_gmt":"2024-07-24T11:03:43","guid":{"rendered":"https:\/\/www.klarairosa.com\/?p=21657"},"modified":"2024-09-19T09:59:28","modified_gmt":"2024-09-19T09:59:28","slug":"zajednicko-kuvanje-sa-antonom","status":"publish","type":"post","link":"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/","title":{"rendered":"K\u00f6z\u00f6s f\u0151z\u00e9s Antonnal"},"content":{"rendered":"<p>Pridru\u017eite nam se <strong>27. jula od 18h u ku\u0107i Klare i Rose (Petefi \u0160andora 15)<\/strong> u zajedni\u010dkom kuvanju <strong>sa Antonom.<\/strong><br class=\"html-br\" \/>.<br class=\"html-br\" \/>Zaronic\u0301emo u umetnost pravljenja hladne supe i jo\u0161 po neke poslastice po izboru na\u0161eg gosta i doma\u0107ina ovog programa, Antona!<br class=\"html-br\" \/>.<br class=\"html-br\" \/>Radionica je besplatna ali su mesta ograni\u010dena. Prijavite se na klarairosa@gmail.com<br class=\"html-br\" \/>.<br class=\"html-br\" \/>Ovaj program je podr\u017ean donacijama gra\u0111ana putem <span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 xzsf02u x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/crowdfunding?__eep__=6&amp;__cft__[0]=AZWAdgKunvxnOeiHmrU6rWoKLUYxFXSNi8jZXeobsaJ9D34uDh3tzxyhCElhTD7rqop-410IJf_V7Oo-f5qdXwlw_LHGySwT-kYMEMgWeOl_xFVa6OGvxqVOuNftIsOS4tnZ12VO9AZK1Tzd_JaPBB7KegRvw18I_gfWzSnGjhAN7Uv9UCRwWAse022C5iBAgmse90vXf3o_wznP1RRhZ8ha&amp;__tn__=*NK*F\">#crowdfunding<\/a><\/span>\u00a0kampanje u sklopu programa\u00a0<span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 x1fey0fg\" tabindex=\"0\" role=\"link\" href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Fwww.instagram.com%2F_u%2Ftragfondacija%3Ffbclid%3DIwZXh0bgNhZW0CMTAAAR2C6SPn5guOCez5j4cH9eomLU29uVZ1Odrgr5ALifZerNV9Jb2BIDPEPDg_aem_qMpfe9SvFpl7SDaU6OWe9g&amp;h=AT1gKhVcQPVZCTotj7a-unI860C8Ddel2oNX7x_NDoRABG_TaQTOLaxlnsE2LSWOxmmvao1mq-Y6J5yG_frswppnbHtd2aC1zAxrv2f3FbWComIyUaiZ6rZMBNNd3DQsYoRk&amp;__tn__=-UK*F&amp;c[0]=AT1N83S0TwMu_DWPg3K0M5Lcc8q_LM9Z8f8mMem04ODtrBaV6tfothGKx_PGyXD-dAIb-5Gns9H1bhsmYBiNJHXJSaXTqSjD_sA4_nP-ygu3K9ys8hkgBbSAVJ7bX3WxrGh9w3TNZz1o8VGHrsBR-5-KSf9-21qGuCRflaQ5SxcObwFDKasBIqCdAvcPBBW3v9gsuBeTLh5A_W-Eb3UKvIcKPyTY1-jlMhHO_w\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">@tragfondacija<\/a><\/span><\/p>\n<p>.<\/p>\n<div  id=\"jtg-21770\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;wheel&quot;:&quot;slide&quot;,&quot;touch&quot;:true,&quot;backdropClick&quot;:&quot;close&quot;,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Close&quot;,&quot;NEXT&quot;:&quot;Next&quot;,&quot;PREV&quot;:&quot;Previous&quot;,&quot;Error&quot;:&quot;The requested content cannot be loaded. Please try again later.&quot;,&quot;PLAY_START&quot;:&quot;Start slideshow&quot;,&quot;PLAY_STOP&quot;:&quot;Pause slideshow&quot;,&quot;FULL_SCREEN&quot;:&quot;Full screen&quot;,&quot;THUMBS&quot;:&quot;Thumbnails&quot;,&quot;DOWNLOAD&quot;:&quot;Download&quot;,&quot;SHARE&quot;:&quot;Share&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;You can close this modal content with the ESC key&quot;,&quot;ERROR&quot;:&quot;Something Went Wrong, Please Try Again Later&quot;,&quot;IMAGE_ERROR&quot;:&quot;Image Not Found&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;HTML Element Not Found&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error Loading AJAX : Not Found&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error Loading AJAX : Forbidden&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error Loading Page&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Toggle zoom level&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Toggle thumbnails&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Toggle slideshow&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Toggle full-screen mode&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-21770&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;,&quot;lightbox_devices&quot;:&quot;both&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21780\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img fetchpriority=\"high\" decoding=\"async\" class=\"pic wp-image-21780\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2.jpg\" title=\"smanjeno\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21779\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-21779\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2.jpg\" title=\"smanjeno_10\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_10-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21776\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-21776\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2.jpg\" title=\"smanjeno_7\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_7-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21771\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21771\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2.jpg\" title=\"smanjeno_2\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_2-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21778\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21778\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2.jpg\" title=\"smanjeno_9\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_9-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21772\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21772\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2.jpg\" title=\"smanjeno_3\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_3-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21773\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21773\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2.jpg\" title=\"smanjeno_4\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_4-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21774\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21774\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2.jpg\" title=\"smanjeno_5\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_5-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21775\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21775\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2.jpg\" title=\"smanjeno_6\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_6-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21777\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21770\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21777\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2.jpg\" title=\"smanjeno_8\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-300x225.jpg\" data-src=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-300x225.jpg\" data-caption=\"\" srcset=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2.jpg 1024w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-300x225.jpg 300w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-768x576.jpg 768w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-16x12.jpg 16w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-800x600.jpg 800w, https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/smanjeno_8-2-700x525.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/#modula-gallery-21770\",\n\t\t\"url\"     : \"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Pridru\u017eite nam se 27. jula od 18h u ku\u0107i Klare i Rose (Petefi \u0160andora 15)&#8230;<\/p>","protected":false},"author":1,"featured_media":21658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[119],"tags":[312,282,417,124,416,140,152,133],"class_list":["post-21657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ostalo","tag-312","tag-community","tag-community-cooking","tag-klara-i-rosa","tag-kuvanje","tag-radionica","tag-subotica","tag-workshop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zajedni\u010dko kuvanje sa Antonom - Klara i Rosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zajedni\u010dko kuvanje sa Antonom - Klara i Rosa\" \/>\n<meta property=\"og:description\" content=\"Pridru\u017eite nam se 27. jula od 18h u ku\u0107i Klare i Rose (Petefi \u0160andora 15)...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/\" \/>\n<meta property=\"og:site_name\" content=\"Klara i Rosa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/klarairosa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T11:03:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T09:59:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/452449363_1282340806146937_7726026052925973524_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Klara i Rosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Klara i Rosa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/\"},\"author\":{\"name\":\"Klara i Rosa\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#\\\/schema\\\/person\\\/e4e7e9e5c8eeeddccf61e4532ae8e6ed\"},\"headline\":\"Zajedni\u010dko kuvanje sa Antonom\",\"datePublished\":\"2024-07-24T11:03:43+00:00\",\"dateModified\":\"2024-09-19T09:59:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.klarairosa.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/452449363_1282340806146937_7726026052925973524_n.jpg\",\"keywords\":[\"2024\",\"community\",\"community cooking\",\"Klara i Rosa\",\"kuvanje\",\"radionica\",\"subotica\",\"workshop\"],\"articleSection\":[\"Ostalo\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/\",\"url\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/\",\"name\":\"Zajedni\u010dko kuvanje sa Antonom - Klara i Rosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.klarairosa.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/452449363_1282340806146937_7726026052925973524_n.jpg\",\"datePublished\":\"2024-07-24T11:03:43+00:00\",\"dateModified\":\"2024-09-19T09:59:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.klarairosa.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/452449363_1282340806146937_7726026052925973524_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.klarairosa.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/452449363_1282340806146937_7726026052925973524_n.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/zajednicko-kuvanje-sa-antonom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.klarairosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zajedni\u010dko kuvanje sa Antonom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/\",\"name\":\"Klara i Rosa\",\"description\":\"Klara i Rosa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#organization\",\"name\":\"Klara i Rosa\",\"url\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klarairosa.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.klarairosa.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.svg\",\"width\":110,\"height\":139,\"caption\":\"Klara i Rosa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/klarairosa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ugklarairosa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.klarairosa.com\\\/en\\\/#\\\/schema\\\/person\\\/e4e7e9e5c8eeeddccf61e4532ae8e6ed\",\"name\":\"Klara i Rosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c83ee539a067b9f57ae5d8999ae286c4f98b5c4bd943b8cbb64f6b0fc1f29e40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c83ee539a067b9f57ae5d8999ae286c4f98b5c4bd943b8cbb64f6b0fc1f29e40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c83ee539a067b9f57ae5d8999ae286c4f98b5c4bd943b8cbb64f6b0fc1f29e40?s=96&d=mm&r=g\",\"caption\":\"Klara i Rosa\"},\"sameAs\":[\"https:\\\/\\\/klarairosa.com\"],\"url\":\"https:\\\/\\\/www.klarairosa.com\\\/hu\\\/author\\\/rosaiklara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zajedni\u010dko kuvanje sa Antonom - Klara i Rosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/","og_locale":"hu_HU","og_type":"article","og_title":"Zajedni\u010dko kuvanje sa Antonom - Klara i Rosa","og_description":"Pridru\u017eite nam se 27. jula od 18h u ku\u0107i Klare i Rose (Petefi \u0160andora 15)...","og_url":"https:\/\/www.klarairosa.com\/hu\/zajednicko-kuvanje-sa-antonom\/","og_site_name":"Klara i Rosa","article_publisher":"https:\/\/www.facebook.com\/klarairosa\/","article_published_time":"2024-07-24T11:03:43+00:00","article_modified_time":"2024-09-19T09:59:28+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/452449363_1282340806146937_7726026052925973524_n.jpg","type":"image\/jpeg"}],"author":"Klara i Rosa","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"Klara i Rosa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#article","isPartOf":{"@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/"},"author":{"name":"Klara i Rosa","@id":"https:\/\/www.klarairosa.com\/en\/#\/schema\/person\/e4e7e9e5c8eeeddccf61e4532ae8e6ed"},"headline":"Zajedni\u010dko kuvanje sa Antonom","datePublished":"2024-07-24T11:03:43+00:00","dateModified":"2024-09-19T09:59:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/"},"wordCount":80,"publisher":{"@id":"https:\/\/www.klarairosa.com\/en\/#organization"},"image":{"@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/452449363_1282340806146937_7726026052925973524_n.jpg","keywords":["2024","community","community cooking","Klara i Rosa","kuvanje","radionica","subotica","workshop"],"articleSection":["Ostalo"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/","url":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/","name":"Zajedni\u010dko kuvanje sa Antonom - Klara i Rosa","isPartOf":{"@id":"https:\/\/www.klarairosa.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#primaryimage"},"image":{"@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/452449363_1282340806146937_7726026052925973524_n.jpg","datePublished":"2024-07-24T11:03:43+00:00","dateModified":"2024-09-19T09:59:28+00:00","breadcrumb":{"@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#primaryimage","url":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/452449363_1282340806146937_7726026052925973524_n.jpg","contentUrl":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2024\/07\/452449363_1282340806146937_7726026052925973524_n.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.klarairosa.com\/zajednicko-kuvanje-sa-antonom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.klarairosa.com\/"},{"@type":"ListItem","position":2,"name":"Zajedni\u010dko kuvanje sa Antonom"}]},{"@type":"WebSite","@id":"https:\/\/www.klarairosa.com\/en\/#website","url":"https:\/\/www.klarairosa.com\/en\/","name":"Kl\u00e1ra \u00e9s Rosa Egyes\u00fclet","description":"Kl\u00e1ra \u00e9s Rosa Egyes\u00fclet","publisher":{"@id":"https:\/\/www.klarairosa.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klarairosa.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/www.klarairosa.com\/en\/#organization","name":"Kl\u00e1ra \u00e9s Rosa Egyes\u00fclet","url":"https:\/\/www.klarairosa.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/www.klarairosa.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2022\/01\/logo.svg","contentUrl":"https:\/\/www.klarairosa.com\/wp-content\/uploads\/2022\/01\/logo.svg","width":110,"height":139,"caption":"Klara i Rosa"},"image":{"@id":"https:\/\/www.klarairosa.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/klarairosa\/","https:\/\/www.instagram.com\/ugklarairosa\/"]},{"@type":"Person","@id":"https:\/\/www.klarairosa.com\/en\/#\/schema\/person\/e4e7e9e5c8eeeddccf61e4532ae8e6ed","name":"Kl\u00e1ra \u00e9s Rosa Egyes\u00fclet","image":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/secure.gravatar.com\/avatar\/c83ee539a067b9f57ae5d8999ae286c4f98b5c4bd943b8cbb64f6b0fc1f29e40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c83ee539a067b9f57ae5d8999ae286c4f98b5c4bd943b8cbb64f6b0fc1f29e40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c83ee539a067b9f57ae5d8999ae286c4f98b5c4bd943b8cbb64f6b0fc1f29e40?s=96&d=mm&r=g","caption":"Klara i Rosa"},"sameAs":["https:\/\/klarairosa.com"],"url":"https:\/\/www.klarairosa.com\/hu\/author\/rosaiklara\/"}]}},"_links":{"self":[{"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/posts\/21657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/comments?post=21657"}],"version-history":[{"count":2,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/posts\/21657\/revisions"}],"predecessor-version":[{"id":21781,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/posts\/21657\/revisions\/21781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/media\/21658"}],"wp:attachment":[{"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/media?parent=21657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/categories?post=21657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.klarairosa.com\/hu\/wp-json\/wp\/v2\/tags?post=21657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}